{"id":25377,"date":"2021-02-10T09:41:00","date_gmt":"2021-02-10T09:41:00","guid":{"rendered":"https:\/\/healthmenowth.com\/?p=25377"},"modified":"2022-02-10T09:45:12","modified_gmt":"2022-02-10T09:45:12","slug":"4-seasonal-affective-disorder-sad","status":"publish","type":"post","link":"https:\/\/healthmenowth.com\/id\/brain-nerve\/4-seasonal-affective-disorder-sad\/","title":{"rendered":"\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25: 4 \u0e24\u0e14\u0e39\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/healthmenowth.com\/seasonal-affective-disorder-sad\/\" data-type=\"page\" data-id=\"25374\">\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 (Seasonal Affective Disorder :SAD)<\/a> \u0e04\u0e37\u0e2d \u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e02\u0e2d\u0e07\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e21\u0e31\u0e01\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e49\u0e19\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e21\u0e31\u0e01\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e24\u0e14\u0e39\u0e2b\u0e19\u0e32\u0e27 \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e01\u0e23\u0e30\u0e15\u0e37\u0e2d\u0e23\u0e37\u0e2d\u0e23\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e21\u0e31\u0e01\u0e08\u0e30\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e21\u0e48\u0e2a\u0e1a\u0e32\u0e22\u0e15\u0e31\u0e27\u0e44\u0e14\u0e49 \u0e1a\u0e48\u0e2d\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e24\u0e14\u0e39\u0e43\u0e1a\u0e44\u0e21\u0e49\u0e1c\u0e25\u0e34 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e49\u0e19\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"\u0e42\u0e23\u0e04\u0e0b-\u0e21\u0e40\u0e28\u0e23-\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14-\u0e01\u0e32\u0e25\u0e43\u0e19\u0e24\u0e14-\u0e43\u0e1a\u0e44\u0e21-\u0e23-\u0e27\u0e07\u0e41\u0e25\u0e30\u0e24\u0e14-\u0e2b\u0e19\u0e32\u0e27\">\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e43\u0e19\u0e24\u0e14\u0e39\u0e43\u0e1a\u0e44\u0e21\u0e49\u0e23\u0e48\u0e27\u0e07\u0e41\u0e25\u0e30\u0e24\u0e14\u0e39\u0e2b\u0e19\u0e32\u0e27<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e32\u0e01\u0e0e\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e24\u0e14\u0e39\u0e2b\u0e19\u0e32\u0e27 \u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2d\u0e32\u0e08\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e20\u0e32\u0e27\u0e30\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e43\u0e19\u0e24\u0e14\u0e39\u0e2b\u0e19\u0e32\u0e27 \u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e01\u0e32\u0e23\u0e19\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e01\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b<\/li><li>\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e2d\u0e22\u0e32\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e25\u0e14\u0e25\u0e07 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e22\u0e32\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e32\u0e23\u0e4c\u0e42\u0e1a\u0e44\u0e2e\u0e40\u0e14\u0e23\u0e15\u0e2a\u0e39\u0e07<\/li><li><a href=\"https:\/\/healthmenowth.com\/obesity\/\" data-type=\"page\" data-id=\"14514\">\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e15\u0e31\u0e27\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19<\/a><\/li><li><a href=\"https:\/\/healthmenowth.com\/diseases\/heart\/fatigue\/\" data-type=\"page\" data-id=\"974\">\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e48\u0e2d\u0e22\u0e25\u0e49\u0e32<\/a> \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e32\u0e14\u0e04\u0e27\u0e32\u0e21\u0e01\u0e23\u0e30\u0e15\u0e37\u0e2d\u0e23\u0e37\u0e2d\u0e23\u0e49\u0e19<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"\u0e42\u0e23\u0e04\u0e0b-\u0e21\u0e40\u0e28\u0e23-\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14-\u0e01\u0e32\u0e25\u0e43\u0e19\u0e24\u0e14-\u0e43\u0e1a\u0e44\u0e21-\u0e1c\u0e25-\u0e41\u0e25\u0e30\u0e24\u0e14-\u0e23-\u0e2d\u0e19\">\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e43\u0e19\u0e24\u0e14\u0e39\u0e43\u0e1a\u0e44\u0e21\u0e49\u0e1c\u0e25\u0e34\u0e41\u0e25\u0e30\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e32\u0e01\u0e0e\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19 \u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e20\u0e32\u0e27\u0e30\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e1a (<a href=\"https:\/\/healthmenowth.com\/diseases\/brain-nerve\/insomnia\/\" data-type=\"page\" data-id=\"13048\">\u0e19\u0e2d\u0e19\u0e44\u0e21\u0e48\u0e2b\u0e25\u0e31\u0e1a<\/a>)<\/li><li><a href=\"https:\/\/healthmenowth.com\/diseases\/digestive-disease\/loss-of-appetite\/\" data-type=\"page\" data-id=\"11847\">\u0e40\u0e1a\u0e37\u0e48\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23<\/a><\/li><li><a href=\"https:\/\/healthmenowth.com\/weigh-loss\/\" data-type=\"page\" data-id=\"14520\">\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e25\u0e14<\/a><\/li><li>\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e1b\u0e31\u0e48\u0e19\u0e1b\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e34\u0e15\u0e01\u0e01\u0e31\u0e07\u0e27\u0e25<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"\u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b-\u0e2d\u0e19\u0e42\u0e23\u0e04\u0e0b-\u0e21\u0e40\u0e28\u0e23-\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14-\u0e01\u0e32\u0e25\">\u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b\u0e49\u0e2d\u0e19\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2b\u0e32\u0e01\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e08\u0e30\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e42\u0e23\u0e04\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e27\u0e30\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e42\u0e14\u0e22\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e2d\u0e32\u0e08\u0e41\u0e22\u0e48\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e44\u0e14\u0e49 \u0e2b\u0e32\u0e01\u0e44\u0e21\u0e48\u0e23\u0e35\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b\u0e49\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e41\u0e22\u0e01\u0e15\u0e31\u0e27\u0e08\u0e32\u0e01\u0e2a\u0e31\u0e07\u0e04\u0e21<\/li><li>\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e33\u0e07\u0e32\u0e19<\/li><li>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e42\u0e17\u0e29<\/li><li>\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e34\u0e14\u0e1b\u0e01\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e08\u0e34\u0e15\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e15\u0e01\u0e01\u0e31\u0e07\u0e27\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e22\u0e32\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1c\u0e34\u0e14\u0e1b\u0e01\u0e15\u0e34<\/li><li>\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e22\u0e32\u0e01\u0e06\u0e48\u0e32\u0e15\u0e31\u0e27\u0e15\u0e32\u0e22<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b\u0e49\u0e2d\u0e19\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e16\u0e49\u0e32\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e08\u0e30\u0e41\u0e22\u0e48\u0e25\u0e07<\/p>\n<div style='text-align:right' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_b4ac56cd9e0b8' class='yasr-visitor-votes'><div id='yasr-vv-second-row-container-b4ac56cd9e0b8'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-b4ac56cd9e0b8'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='25377'\r\n                                      data-rating='4.7'\r\n                                      data-rater-starsize='32'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='f4c8fc107c'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-b4ac56cd9e0b8\"><span id=\"yasr-vv-text-container-b4ac56cd9e0b8\" class=\"yasr-vv-text-container\">[Total: <span id=\"yasr-vv-votes-number-container-b4ac56cd9e0b8\">3<\/span>  Average: <span id=\"yasr-vv-average-container-b4ac56cd9e0b8\">4.7<\/span>]<\/span><\/div><div id='yasr-vv-loader-b4ac56cd9e0b8' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-b4ac56cd9e0b8'\r\n                              class='yasr-vv-bottom-container'\r\n                              style='display:none'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div>","protected":false},"excerpt":{"rendered":"<p>\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 (Seasonal Affective Disorder :SAD) \u0e04\u0e37\u0e2d \u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e02\u0e2d\u0e07\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e21\u0e31\u0e01\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e49\u0e19\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e21\u0e31\u0e01\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e24\u0e14\u0e39\u0e2b\u0e19\u0e32\u0e27 \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e01\u0e23\u0e30\u0e15\u0e37\u0e2d\u0e23\u0e37\u0e2d\u0e23\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e21\u0e31\u0e01\u0e08\u0e30\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e21\u0e48\u0e2a\u0e1a\u0e32\u0e22\u0e15\u0e31\u0e27\u0e44\u0e14\u0e49 \u0e1a\u0e48\u0e2d\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e24\u0e14\u0e39\u0e43\u0e1a\u0e44\u0e21\u0e49\u0e1c\u0e25\u0e34 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e49\u0e19\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19 \u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e43\u0e19\u0e24\u0e14\u0e39\u0e43\u0e1a\u0e44\u0e21\u0e49\u0e23\u0e48\u0e27\u0e07\u0e41\u0e25\u0e30\u0e24\u0e14\u0e39\u0e2b\u0e19\u0e32\u0e27 \u0e2d\u0e32\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e32\u0e01\u0e0e\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e24\u0e14\u0e39\u0e2b\u0e19\u0e32\u0e27 \u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2d\u0e32\u0e08\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e20\u0e32\u0e27\u0e30\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e43\u0e19\u0e24\u0e14\u0e39\u0e2b\u0e19\u0e32\u0e27 \u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07: \u0e01\u0e32\u0e23\u0e19\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e01\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b \u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e2d\u0e22\u0e32\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e25\u0e14\u0e25\u0e07 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e22\u0e32\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e32\u0e23\u0e4c\u0e42\u0e1a\u0e44\u0e2e\u0e40\u0e14\u0e23\u0e15\u0e2a\u0e39\u0e07 \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e15\u0e31\u0e27\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e48\u0e2d\u0e22\u0e25\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e32\u0e14\u0e04\u0e27\u0e32\u0e21\u0e01\u0e23\u0e30\u0e15\u0e37\u0e2d\u0e23\u0e37\u0e2d\u0e23\u0e49\u0e19 \u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e43\u0e19\u0e24\u0e14\u0e39\u0e43\u0e1a\u0e44\u0e21\u0e49\u0e1c\u0e25\u0e34\u0e41\u0e25\u0e30\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19 \u0e2d\u0e32\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e32\u0e01\u0e0e\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19 \u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e20\u0e32\u0e27\u0e30\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07: \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e1a (\u0e19\u0e2d\u0e19\u0e44\u0e21\u0e48\u0e2b\u0e25\u0e31\u0e1a) \u0e40\u0e1a\u0e37\u0e48\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e25\u0e14 \u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e1b\u0e31\u0e48\u0e19\u0e1b\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e34\u0e15\u0e01\u0e01\u0e31\u0e07\u0e27\u0e25 \u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b\u0e49\u0e2d\u0e19\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e2b\u0e32\u0e01\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e08\u0e30\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e42\u0e23\u0e04\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e27\u0e30\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e42\u0e14\u0e22\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e2d\u0e32\u0e08\u0e41\u0e22\u0e48\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e44\u0e14\u0e49 \u0e2b\u0e32\u0e01\u0e44\u0e21\u0e48\u0e23\u0e35\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b\u0e49\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07: \u0e41\u0e22\u0e01\u0e15\u0e31\u0e27\u0e08\u0e32\u0e01\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e42\u0e17\u0e29 \u0e04\u0e27\u0e32\u0e21\u0e1c\u0e34\u0e14\u0e1b\u0e01\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e08\u0e34\u0e15\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e15\u0e01\u0e01\u0e31\u0e07\u0e27\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e22\u0e32\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1c\u0e34\u0e14\u0e1b\u0e01\u0e15\u0e34 \u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e22\u0e32\u0e01\u0e06\u0e48\u0e32\u0e15\u0e31\u0e27\u0e15\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b\u0e49\u0e2d\u0e19\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e16\u0e49\u0e32\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e08\u0e30\u0e41\u0e22\u0e48\u0e25\u0e07 [Total:<a class=\"more-link\" href=\"https:\/\/healthmenowth.com\/id\/brain-nerve\/4-seasonal-affective-disorder-sad\/\">Lanjutkan membaca <span class=\"screen-reader-text\">&#8220;\u0e42\u0e23\u0e04\u0e0b\u0e36\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25: 4 \u0e24\u0e14\u0e39\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e28\u0e23\u0e49\u0e32&#8221;<\/span><\/a><\/p>\n","protected":false},"author":158819400,"featured_media":2479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[331419674],"tags":[280260937],"class_list":["post-25377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brain-nerve","tag-280260937","entry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"id","enabled_languages":["th","zh","id","ja","ko","ru"],"languages":{"th":{"title":true,"content":true,"excerpt":false},"zh":{"title":false,"content":false,"excerpt":false},"id":{"title":false,"content":false,"excerpt":false},"ja":{"title":false,"content":false,"excerpt":false},"ko":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false}}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":3,"sum_votes":14},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/healthmenowth.com\/wp-content\/uploads\/2019\/10\/pexels-photo-1573823.jpeg?fit=1604%2C1300&ssl=1","jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pb2JDV-6Bj","_links":{"self":[{"href":"https:\/\/healthmenowth.com\/id\/wp-json\/wp\/v2\/posts\/25377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/healthmenowth.com\/id\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/healthmenowth.com\/id\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/healthmenowth.com\/id\/wp-json\/wp\/v2\/users\/158819400"}],"replies":[{"embeddable":true,"href":"https:\/\/healthmenowth.com\/id\/wp-json\/wp\/v2\/comments?post=25377"}],"version-history":[{"count":2,"href":"https:\/\/healthmenowth.com\/id\/wp-json\/wp\/v2\/posts\/25377\/revisions"}],"predecessor-version":[{"id":25379,"href":"https:\/\/healthmenowth.com\/id\/wp-json\/wp\/v2\/posts\/25377\/revisions\/25379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/healthmenowth.com\/id\/wp-json\/wp\/v2\/media\/2479"}],"wp:attachment":[{"href":"https:\/\/healthmenowth.com\/id\/wp-json\/wp\/v2\/media?parent=25377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/healthmenowth.com\/id\/wp-json\/wp\/v2\/categories?post=25377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/healthmenowth.com\/id\/wp-json\/wp\/v2\/tags?post=25377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}