{"id":26411,"date":"2022-03-03T09:14:32","date_gmt":"2022-03-03T09:14:32","guid":{"rendered":"https:\/\/healthmenowth.com\/?page_id=26411"},"modified":"2022-03-03T09:14:34","modified_gmt":"2022-03-03T09:14:34","slug":"treatments","status":"publish","type":"page","link":"https:\/\/healthmenowth.com\/ko\/diseases\/bladder\/molar-pregnancy\/treatments\/","title":{"rendered":"\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e23\u0e20\u0e4c\u0e44\u0e02\u0e48\u0e1b\u0e25\u0e32\u0e2d\u0e38\u0e01"},"content":{"rendered":"<div id=\"ccchildpages-1\" class=\"ccchildpages ccflex threecol simple ccclearfix\"><ul class=\"ccchildpages_list ccclearfix\"><li class=\"page_item page-item-26410\"><a href=\"https:\/\/healthmenowth.com\/ko\/diseases\/bladder\/molar-pregnancy\/symptoms\/\">\u0e2d\u0e32\u0e01\u0e32\u0e23 \u0e04\u0e23\u0e23\u0e20\u0e4c\u0e44\u0e02\u0e48\u0e1b\u0e25\u0e32\u0e2d\u0e38\u0e01<\/a><\/li>\n<li class=\"page_item page-item-26411\"><a href=\"https:\/\/healthmenowth.com\/ko\/diseases\/bladder\/molar-pregnancy\/treatments\/\">\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e23\u0e20\u0e4c\u0e44\u0e02\u0e48\u0e1b\u0e25\u0e32\u0e2d\u0e38\u0e01<\/a><\/li><\/ul><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e2b\u0e32\u0e01\u0e2a\u0e07\u0e2a\u0e31\u0e22\u0e04\u0e27\u0e23\u0e2a\u0e48\u0e07\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e2e\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e40\u0e2d\u0e0b\u0e0b\u0e35\u0e08\u0e35\u0e43\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e2a\u0e2a\u0e32\u0e27\u0e30\u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48 \u0e1e\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e1b\u0e01\u0e15\u0e34<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e2d\u0e32\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e31\u0e25\u0e15\u0e23\u0e32\u0e0b\u0e32\u0e27\u0e19\u0e14\u0e4c \u0e15\u0e23\u0e27\u0e08\u0e0a\u0e34\u0e49\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e16\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e23\u0e04\u0e19\u0e35\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e2d\u0e32\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e02\u0e39\u0e14\u0e21\u0e14\u0e25\u0e39\u0e01\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e04\u0e27\u0e23\u0e01\u0e34\u0e19\u0e22\u0e32\u0e40\u0e21\u0e47\u0e14\u0e04\u0e38\u0e21\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e19\u0e32\u0e19 6 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e39\u0e14 \u0e21\u0e14\u0e25\u0e39\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e21\u0e14\u0e25\u0e39\u0e01\u0e15\u0e32\u0e21\u0e41\u0e15\u0e48\u0e2a\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e16\u0e49\u0e32\u0e2d\u0e32\u0e22\u0e38 \u0e21\u0e32\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d \u0e2d\u0e32\u0e08\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e40\u0e2d\u0e32\u0e21\u0e14\u0e25\u0e39\u0e01\u0e2d\u0e2d\u0e01(\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e14\u0e21\u0e22\u0e32\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e04\u0e27\u0e23\u0e43\u0e2b\u0e49\u0e22\u0e32\u0e1b\u0e34\u0e14\u0e01\u0e31\u0e49\u0e19\u0e1a\u0e35\u0e15\u0e32\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07<a href=\"https:\/\/healthmenowth.com\/th\/endocrine-system\/hyperthyroidism\/\">\u0e20\u0e32\u0e27\u0e30\u0e15\u0e48\u0e2d\u0e21\u0e44\u0e17\u0e23\u0e2d\u0e22\u0e14\u0e4c\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e01\u0e34\u0e19<\/a>)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19&nbsp;\u0e04\u0e27\u0e23\u0e19\u0e31\u0e14\u0e21\u0e32\u0e15\u0e23\u0e27\u0e08\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e2d\u0e0b\u0e0b\u0e35\u0e08\u0e35\u0e43\u0e19\u0e1b\u0e31\u0e2a\u0e2a\u0e32\u0e27\u0e30 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c\u0e1b\u0e2d\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22 2 \u0e1b\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e27\u0e48\u0e32 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e01\u0e33\u0e40\u0e23\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e30\u0e40\u0e23\u0e47\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e16\u0e49\u0e32\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e2d\u0e0a\u0e0b\u0e35\u0e08\u0e35\u0e44\u0e21\u0e48\u0e25\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e21\u0e30\u0e40\u0e23\u0e47\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e21\u0e42\u0e17\u0e40\u0e17\u0e23\u0e01\u0e40\u0e0b\u0e15(methotrexate)\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e14\u0e01\u0e15\u0e34\u0e42\u0e19\u0e44\u0e21\u0e0b\u0e34\u0e19&nbsp; (dactinomycin) \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e42\u0e23\u0e04\u0e17\u0e38\u0e40\u0e25\u0e32\u0e25\u0e07 \u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e31\u0e14\u0e21\u0e14\u0e25\u0e39\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e27\u0e23\u0e01\u0e34\u0e19\u0e22\u0e32\u0e40\u0e21\u0e47\u0e14\u0e04\u0e38\u0e21\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e19\u0e32\u0e19 12 \u0e40\u0e14\u0e37\u0e2d\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e43\u0e19\u0e23\u0e32\u0e22\u0e17\u0e35\u0e48\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e30\u0e40\u0e23\u0e47\u0e07\u0e40\u0e22\u0e37\u0e48\u0e2d\u0e23\u0e01 (choriocarcinoma)&nbsp;\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e21\u0e30\u0e40\u0e23\u0e47\u0e07 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e2b\u0e32\u0e22\u0e02\u0e32\u0e14\u0e44\u0e14\u0e49\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30&nbsp;100 \u0e16\u0e49\u0e32\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19&nbsp;\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 60-80&nbsp;\u0e16\u0e49\u0e32\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19<\/p>\n<div style='text-align:right' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_d036ef4027adb' class='yasr-visitor-votes'><div id='yasr-vv-second-row-container-d036ef4027adb'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-d036ef4027adb'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='26411'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='32'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='f4c8fc107c'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-d036ef4027adb\"><span id=\"yasr-vv-text-container-d036ef4027adb\" class=\"yasr-vv-text-container\">[Total: <span id=\"yasr-vv-votes-number-container-d036ef4027adb\">0<\/span>  Average: <span id=\"yasr-vv-average-container-d036ef4027adb\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-d036ef4027adb' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-d036ef4027adb'\r\n                              class='yasr-vv-bottom-container'\r\n                              style='display:none'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e2b\u0e32\u0e01\u0e2a\u0e07\u0e2a\u0e31\u0e22\u0e04\u0e27\u0e23\u0e2a\u0e48\u0e07\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e2e\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e40\u0e2d\u0e0b\u0e0b\u0e35\u0e08\u0e35\u0e43\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e2a\u0e2a\u0e32\u0e27\u0e30\u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48 \u0e1e\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e1b\u0e01\u0e15\u0e34 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e2d\u0e32\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e31\u0e25\u0e15\u0e23\u0e32\u0e0b\u0e32\u0e27\u0e19\u0e14\u0e4c \u0e15\u0e23\u0e27\u0e08\u0e0a\u0e34\u0e49\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e16\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e23\u0e04\u0e19\u0e35\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e2d\u0e32\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e02\u0e39\u0e14\u0e21\u0e14\u0e25\u0e39\u0e01\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e04\u0e27\u0e23\u0e01\u0e34\u0e19\u0e22\u0e32\u0e40\u0e21\u0e47\u0e14\u0e04\u0e38\u0e21\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e19\u0e32\u0e19 6 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e39\u0e14 \u0e21\u0e14\u0e25\u0e39\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e21\u0e14\u0e25\u0e39\u0e01\u0e15\u0e32\u0e21\u0e41\u0e15\u0e48\u0e2a\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e16\u0e49\u0e32\u0e2d\u0e32\u0e22\u0e38 \u0e21\u0e32\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d \u0e2d\u0e32\u0e08\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e40\u0e2d\u0e32\u0e21\u0e14\u0e25\u0e39\u0e01\u0e2d\u0e2d\u0e01(\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e14\u0e21\u0e22\u0e32\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e04\u0e27\u0e23\u0e43\u0e2b\u0e49\u0e22\u0e32\u0e1b\u0e34\u0e14\u0e01\u0e31\u0e49\u0e19\u0e1a\u0e35\u0e15\u0e32\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e27\u0e30\u0e15\u0e48\u0e2d\u0e21\u0e44\u0e17\u0e23\u0e2d\u0e22\u0e14\u0e4c\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e01\u0e34\u0e19) &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19&nbsp;\u0e04\u0e27\u0e23\u0e19\u0e31\u0e14\u0e21\u0e32\u0e15\u0e23\u0e27\u0e08\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e2d\u0e0b\u0e0b\u0e35\u0e08\u0e35\u0e43\u0e19\u0e1b\u0e31\u0e2a\u0e2a\u0e32\u0e27\u0e30 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c\u0e1b\u0e2d\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22 2 \u0e1b\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e27\u0e48\u0e32 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e01\u0e33\u0e40\u0e23\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e30\u0e40\u0e23\u0e47\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e16\u0e49\u0e32\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e2d\u0e0a\u0e0b\u0e35\u0e08\u0e35\u0e44\u0e21\u0e48\u0e25\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e21\u0e30\u0e40\u0e23\u0e47\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e21\u0e42\u0e17\u0e40\u0e17\u0e23\u0e01\u0e40\u0e0b\u0e15(methotrexate)\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e14\u0e01\u0e15\u0e34\u0e42\u0e19\u0e44\u0e21\u0e0b\u0e34\u0e19&nbsp; (dactinomycin) \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e42\u0e23\u0e04\u0e17\u0e38\u0e40\u0e25\u0e32\u0e25\u0e07 \u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e31\u0e14\u0e21\u0e14\u0e25\u0e39\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e27\u0e23\u0e01\u0e34\u0e19\u0e22\u0e32\u0e40\u0e21\u0e47\u0e14\u0e04\u0e38\u0e21\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e19\u0e32\u0e19 12 \u0e40\u0e14\u0e37\u0e2d\u0e19 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e43\u0e19\u0e23\u0e32\u0e22\u0e17\u0e35\u0e48\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e30\u0e40\u0e23\u0e47\u0e07\u0e40\u0e22\u0e37\u0e48\u0e2d\u0e23\u0e01 (choriocarcinoma)&nbsp;\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e21\u0e30\u0e40\u0e23\u0e47\u0e07 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e2b\u0e32\u0e22\u0e02\u0e32\u0e14\u0e44\u0e14\u0e49\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30&nbsp;100 \u0e16\u0e49\u0e32\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19&nbsp;\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 60-80&nbsp;\u0e16\u0e49\u0e32\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 [Total: 0 Average: 0]<\/p>\n","protected":false},"author":158819400,"featured_media":0,"parent":4412,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"class_list":["post-26411","page","type-page","status-publish","hentry","entry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"ko","enabled_languages":["th","zh","id","ja","ko","ru"],"languages":{"th":{"title":true,"content":true,"excerpt":false},"zh":{"title":false,"content":false,"excerpt":false},"id":{"title":false,"content":false,"excerpt":false},"ja":{"title":false,"content":false,"excerpt":false},"ko":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false}}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/Pb2JDV-6RZ","_links":{"self":[{"href":"https:\/\/healthmenowth.com\/ko\/wp-json\/wp\/v2\/pages\/26411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/healthmenowth.com\/ko\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/healthmenowth.com\/ko\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/healthmenowth.com\/ko\/wp-json\/wp\/v2\/users\/158819400"}],"replies":[{"embeddable":true,"href":"https:\/\/healthmenowth.com\/ko\/wp-json\/wp\/v2\/comments?post=26411"}],"version-history":[{"count":2,"href":"https:\/\/healthmenowth.com\/ko\/wp-json\/wp\/v2\/pages\/26411\/revisions"}],"predecessor-version":[{"id":26423,"href":"https:\/\/healthmenowth.com\/ko\/wp-json\/wp\/v2\/pages\/26411\/revisions\/26423"}],"up":[{"embeddable":true,"href":"https:\/\/healthmenowth.com\/ko\/wp-json\/wp\/v2\/pages\/4412"}],"wp:attachment":[{"href":"https:\/\/healthmenowth.com\/ko\/wp-json\/wp\/v2\/media?parent=26411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}